{"id":1160,"date":"2016-04-11T19:08:58","date_gmt":"2016-04-11T17:08:58","guid":{"rendered":"http:\/\/www.steffenkirchner.de\/blog\/?p=1160"},"modified":"2018-09-17T15:20:20","modified_gmt":"2018-09-17T13:20:20","slug":"lebenslektionen","status":"publish","type":"post","link":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/","title":{"rendered":"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben"},"content":{"rendered":"<p>Die folgenden drei Lebenslektionen zu erfahren, war nicht immer einfach und angenehm. Diese Lebenslektionen dann nach und nach wirklich zu verstehen, haben mein Leben im Laufe der letzten 10 Jahre allerdings entscheidend positiv beeinflusst und ver\u00e4ndert. Ich bin sicher, sie werden auch f\u00fcr Dich in vielen Lebensbereichen sehr wertvoll sein.\u00a0 <!--more--><\/p>\n<p><strong>1. Lebenslektion: &#8222;Wer jemand anderen an die kurze Leine nimmt, fesselt sich damit auch selbst.&#8220;<\/strong><\/p>\n<p>Diese Lebensregel gilt f\u00fcr die F\u00fchrung von Mitarbeitern in Unternehmen, f\u00fcr die Arbeit mit Sportlern durch ihre Trainer, f\u00fcr die Erziehung von Kindern und auch f\u00fcr den gegenseitigen Umgang in einer Partnerschaft. Wer andere an der kurzen Leine h\u00e4lt und st\u00e4ndig kontrolliert, beraubt sich auch selbst seiner eigenen Freiheit. In dem Ma\u00dfe, wie wir andere Menschen frei lassen, befreien wir uns auch selbst. Wer Fortschritt will, darf niemanden fesseln und kontrollieren. Mache Dir bewusst, dass das Gegenteil von Liebe nicht Hass ist, sondern Angst. Wer Angst hat, kontrolliert, da er misstraut. Wer andere an die kurze Leine nimmt, um sie zu kontrollieren, hat eine Lebensaufgabe, die mit ihm selbst zu tun hat. Er muss an seinem eigenen Selbstvertrauen, seinem Vertrauen zum Leben und seinem Selbstwertgef\u00fchl arbeiten. Andernfalls fesselt er nicht nur den Kontrollierten, sondern auch sich selbst.<\/p>\n<p><strong>2. Lebenslektion: &#8222;Den wahren Charakter eines Menschen erkennst du nicht bei der ersten, sondern bei der letzten Begegnung.&#8220;<br \/>\n<\/strong><br \/>\nOftmals f\u00e4llen wir \u00fcber andere Personen vorschnell ein Urteil &#8211; manchmal \u00fcbertrieben positiv oder auch negativ. Wir nehmen Optik, Worte oder Gesten eines Menschen wahr und stecken ihn in eine unserer mentalen Schubladen. Dabei nehmen wir unser Gegen\u00fcber nie so wahr, wie er\/sie ist, sondern so, wie wir ihn\/sie sehen. Die wahre Qualit\u00e4t einer Pers\u00f6nlichkeit zeigt sich immer erst am Ende, da man zu diesem Zeitpunkt davon ausgeht, dass der gemeinsame Weg an dieser Stelle endet. In diesem Moment, h\u00f6ren alle Manipulationen und Schauspielereien auf und Menschen zeigen ihr wahres Gesicht. Manchmal gibt es positive, manchmal auch negative \u00dcberraschungen.<br \/>\nDie wichtigste Frage f\u00fcr Dich selbst dabei ist: Welches Gef\u00fchl hast DU bei anderen Menschen bei der letzten Begegnung hinterlassen?<\/p>\n<p><strong><br \/>\n3. Lebenslektion: &#8222;Die Menschen, die Dich zu Beginn am meisten kritisiert, untersch\u00e4tzt und ausgelacht haben, werden zu den gr\u00f6\u00dften Bewunderern und Neidern Deines Erfolgs von morgen.&#8220;<\/strong><\/p>\n<p>Neid und Widerstand ist eine Form von Anerkennung. Sehe es als Kompliment, denn ob jemand Deiner Meinung ist oder nicht, ist sekund\u00e4r. Wenn aber jemand Deinen Weg attackiert, in Worten oder Handlungen, zeigt dass, das du ernst zu nehmen bist, ansonsten w\u00fcrde man Dich ignorieren.<br \/>\nUnabh\u00e4ngig davon merke Dir f\u00fcr immer: Es gibt Menschen die Dich versuchen klein zu machen, Dich auslachen oder Dir sagen dass du etwas nicht kannst und du mal wieder realistisch bzw. vern\u00fcnftig werden sollst. Und all diese Personen haben eins gemeinsam: Sie sind selbst unzufrieden mit sich und ihrem Leben und stehen auf ihrer pers\u00f6nlichen Erfolgsleiter nach dem eigenem Gef\u00fchl unter Dir. Wirkliche Erfolgspers\u00f6nlichkeiten werden Dich niemals in dieser Form versuchen klein zu halten oder Dir gro\u00dfe Ziele und Tr\u00e4ume ausreden. Runterziehen wollen\/k\u00f6nnen Dich nur immer diejenigen, die unter Dir stehen. Menschen die oben auf sind, versuchen immer, andere Menschen zu unterst\u00fctzen auf dem Weg der pers\u00f6nlichen Entwicklung &#8222;hoch zu ziehen&#8220;.<\/p>\n<p><strong>Ich hoffe diese drei Lebenslektionen waren wertvoll f\u00fcr Dich. Schreibe mir gerne als Kommentar Deine Gedanken dazu. Ich w\u00fcrde mich freuen, Dich einmal bei einem meiner Seminar pers\u00f6nlich kennenzulernen.<\/strong><\/p>\n<p><strong>Herzliche Gr\u00fc\u00dfe, Dein <a href=\"https:\/\/www.facebook.com\/steffenkirchner.de\/\">Steffen Kirchner<\/a><\/strong><\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Die folgenden drei Lebenslektionen zu erfahren, war nicht immer einfach und angenehm. Diese Lebenslektionen dann nach und nach wirklich zu verstehen, haben mein Leben im Laufe der letzten 10 Jahre allerdings entscheidend positiv beeinflusst und ver\u00e4ndert. Ich bin sicher, sie &hellip; <a href=\"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[20,1,25,16,26,22,23],"tags":[239,525,182,5,283,522,523,132,424,524],"class_list":["post-1160","post","type-post","status-publish","format-standard","hentry","category-erfolgsimpulse","category-lebensglueck","category-lebenslektionen","category-motivation","category-erlebnisse","category-spitzenleistung-beruf","category-spitzenleistung-leben","tag-angst","tag-charakter","tag-erfolgsregeln","tag-erkenntnis","tag-hass","tag-lebenslektionen","tag-lektion","tag-liebe","tag-loslassen","tag-weisheit"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben<\/title>\n<meta name=\"description\" content=\"Die folgenden 3 Lebenslektionen zu verstehen, werden auch f\u00fcr Dich und Dein Lebensgl\u00fcck in vielen Bereichen \u00e4u\u00dferst hilfreich sein.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben\" \/>\n<meta property=\"og:description\" content=\"Die folgenden 3 Lebenslektionen zu verstehen, werden auch f\u00fcr Dich und Dein Lebensgl\u00fcck in vielen Bereichen \u00e4u\u00dferst hilfreich sein.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen Kirchner Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/steffenkirchner.de\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/de-de.facebook.com\/steffenkirchner.de\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-11T17:08:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-17T13:20:20+00:00\" \/>\n<meta name=\"author\" content=\"Steffen Kirchner\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen Kirchner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/\"},\"author\":{\"name\":\"Steffen Kirchner\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"headline\":\"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben\",\"datePublished\":\"2016-04-11T17:08:58+00:00\",\"dateModified\":\"2018-09-17T13:20:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/\"},\"wordCount\":599,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"keywords\":[\"Angst\",\"Charakter\",\"Erfolgsregeln\",\"Erkenntnis\",\"Hass\",\"Lebenslektionen\",\"Lektion\",\"Liebe\",\"Loslassen\",\"Weisheit\"],\"articleSection\":[\"Erfolgsimpulse\",\"Lebensgl\u00fcck\",\"Lebenslektionen\",\"Motivation\",\"Pers\u00f6nliche Erlebnisse\",\"Spitzenleistung im Beruf\",\"Spitzenleistung im Leben\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/\",\"name\":\"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\"},\"datePublished\":\"2016-04-11T17:08:58+00:00\",\"dateModified\":\"2018-09-17T13:20:20+00:00\",\"description\":\"Die folgenden 3 Lebenslektionen zu verstehen, werden auch f\u00fcr Dich und Dein Lebensgl\u00fcck in vielen Bereichen \u00e4u\u00dferst hilfreich sein.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/lebenslektionen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\",\"name\":\"Steffen Kirchner Blog\",\"description\":\"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\",\"name\":\"Steffen Kirchner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"caption\":\"Steffen Kirchner\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.steffenkirchner.de\",\"https:\\\/\\\/de-de.facebook.com\\\/steffenkirchner.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/steffen.kirchner\\\/channel\\\/?hl=de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/steffen-kirchner\\\/?originalSubdomain=de\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZVCBY3k27CCmKxMNzLtedA\"],\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/author\\\/admin\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben","description":"Die folgenden 3 Lebenslektionen zu verstehen, werden auch f\u00fcr Dich und Dein Lebensgl\u00fcck in vielen Bereichen \u00e4u\u00dferst hilfreich sein.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/","og_locale":"de_DE","og_type":"article","og_title":"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben","og_description":"Die folgenden 3 Lebenslektionen zu verstehen, werden auch f\u00fcr Dich und Dein Lebensgl\u00fcck in vielen Bereichen \u00e4u\u00dferst hilfreich sein.","og_url":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/","og_site_name":"Steffen Kirchner Blog","article_publisher":"https:\/\/de-de.facebook.com\/steffenkirchner.de\/","article_author":"https:\/\/de-de.facebook.com\/steffenkirchner.de\/","article_published_time":"2016-04-11T17:08:58+00:00","article_modified_time":"2018-09-17T13:20:20+00:00","author":"Steffen Kirchner","twitter_misc":{"Verfasst von":"Steffen Kirchner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/#article","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/"},"author":{"name":"Steffen Kirchner","@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"headline":"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben","datePublished":"2016-04-11T17:08:58+00:00","dateModified":"2018-09-17T13:20:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/"},"wordCount":599,"commentCount":7,"publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"keywords":["Angst","Charakter","Erfolgsregeln","Erkenntnis","Hass","Lebenslektionen","Lektion","Liebe","Loslassen","Weisheit"],"articleSection":["Erfolgsimpulse","Lebensgl\u00fcck","Lebenslektionen","Motivation","Pers\u00f6nliche Erlebnisse","Spitzenleistung im Beruf","Spitzenleistung im Leben"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/","url":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/","name":"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#website"},"datePublished":"2016-04-11T17:08:58+00:00","dateModified":"2018-09-17T13:20:20+00:00","description":"Die folgenden 3 Lebenslektionen zu verstehen, werden auch f\u00fcr Dich und Dein Lebensgl\u00fcck in vielen Bereichen \u00e4u\u00dferst hilfreich sein.","breadcrumb":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.steffenkirchner.de\/blog\/lebenslektionen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.steffenkirchner.de\/blog\/"},{"@type":"ListItem","position":2,"name":"3 Lebenslektionen, die mein Leben komplett ver\u00e4ndert haben"}]},{"@type":"WebSite","@id":"https:\/\/www.steffenkirchner.de\/blog\/#website","url":"https:\/\/www.steffenkirchner.de\/blog\/","name":"Steffen Kirchner Blog","description":"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner","publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.steffenkirchner.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4","name":"Steffen Kirchner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","caption":"Steffen Kirchner"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.steffenkirchner.de","https:\/\/de-de.facebook.com\/steffenkirchner.de\/","https:\/\/www.instagram.com\/steffen.kirchner\/channel\/?hl=de","https:\/\/www.linkedin.com\/in\/steffen-kirchner\/?originalSubdomain=de","https:\/\/www.youtube.com\/channel\/UCZVCBY3k27CCmKxMNzLtedA"],"url":"https:\/\/www.steffenkirchner.de\/blog\/author\/admin\/"},false]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4QCGC-iI","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/1160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/comments?post=1160"}],"version-history":[{"count":3,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/1160\/revisions"}],"predecessor-version":[{"id":1163,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/1160\/revisions\/1163"}],"wp:attachment":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/media?parent=1160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/categories?post=1160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/tags?post=1160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}