{"id":1220,"date":"2016-08-18T16:08:11","date_gmt":"2016-08-18T14:08:11","guid":{"rendered":"http:\/\/www.steffenkirchner.de\/blog\/?p=1220"},"modified":"2018-09-17T13:57:46","modified_gmt":"2018-09-17T11:57:46","slug":"gutes-an-problemen","status":"publish","type":"post","link":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/","title":{"rendered":"Probleme? Was ist das Gute daran?"},"content":{"rendered":"<p>Es gibt mehrere universelle Gesetzm\u00e4\u00dfigkeiten. Eines davon ist das Gesetz der Polarit\u00e4t. Dieses besagt, dass es von allem in der Welt immer zwei Pole geben muss &#8211; Schwarz &amp; Wei\u00df, Licht &amp; Schatten, Plus &amp; Minus, Tag &amp; Nacht etc.. Das bedeutet, dass hinter allen R\u00fcckschl\u00e4gen, Niederlagen, Entt\u00e4uschungen, Problemen und Schicksalsschl\u00e4gen auch ein positiver Gegenpol steht. In diesem Artikel zeige ich Dir, wie Du dieses Polarit\u00e4tsprinzip zu Deinem Vorteil nutzen kannst, um schwierige Situationen im Leben besser zu meistern.<\/p>\n<p><!--more-->Zuallererst m\u00f6chte ich Dir eine kleine Geschichte erz\u00e4hlen, die zu diesem Thema gut passt. Die Geschichte hei\u00dft &#8222;Der Schiffbr\u00fcchige&#8220; und geht wie folgt:<br \/>\n<em>Nach einem gro\u00dfen Schiffsungl\u00fcck wird der einzige \u00dcberlebende an den Strand einer einsamen und unbewohnten Insel gesp\u00fclt. Tag f\u00fcr Tag hielt er Ausschau nach einem Schiff am Horizont. <\/em><em>Nach vielen Tagen ergebnisloser Ausschau nach einem Schiff, das ihn retten w\u00fcrde, baute er sich eine kleine H\u00fctte aus Holz, um sich darin vor Wind und Wetter besser zu sch\u00fctzen. Eines Tages kam er von einem Ausflug auf der Insel zur\u00fcck und stellte fest, dass seine H\u00fctte in Flammen stand. In der H\u00fctte war alles, was er noch besa\u00df und bisher gesammelt hatte, um \u00fcberleben zu k\u00f6nnen. Nun hatte er alles verloren und seine Stimmung wechselte von Wutanf\u00e4llen \u00fcber tiefe Entt\u00e4uschung bis hin zu Phasen kompletter Verzweiflung.<\/em><br \/>\n<em> Am n\u00e4chsten Morgen wachte er durch das Motorger\u00e4usch eines Bootes auf, das sich der Insel n\u00e4herte. Man kam, um ihn zu retten. \u201cWoher wusstet ihr, dass ich hier bin?\u201d, fragte er seine Retter. Die Retter antworteten: \u201cWir haben Dein Rauchsignal gesehen, mit dem Du um Hilfe gerufen hast.&#8220;<\/em><\/p>\n<p><strong>Schicksalsschl\u00e4ge sind Wendepunkte des Lebens<\/strong><\/p>\n<p>Was sagt uns diese Geschichte? Es ist nat\u00fcrlich total nachvollziehbar, dass der Schiffbr\u00fcchige am Boden zerst\u00f6rt war, als er seine abgebrannte H\u00fctte entdeckte. In diesem Moment der tiefen Entt\u00e4uschung oder des \u00c4rgers k\u00f6nnen wir oftmals nicht den positiven Sinn von bestimmten Vorkommnissen erkennen. Vielleicht auch deswegen, weil alles, rein logisch betrachtet, einfach keinen Sinn macht. Es f\u00fchlt sich einfach nur unfair an, dass man schon wieder vom Leben einen dicken Kn\u00fcppel zwischen die Beine geworfen bekommen hat. Man f\u00fchlt sich ungerecht behandelt, benachteiligt, einsam und verraten. Ja, das Leben kann manchmal echt ein Arschloch sein.<\/p>\n<p>Doch was kann man nun tun? Ganz wichtig ist meiner Meinung nach: Du darfst erstmal traurig sein. Ja richtig geh\u00f6rt, Schluss mit der ewigen Positiv-Denkerei! Du darfst sauer sein, Jammern, Schimpfen, Dich beschweren und vor Wut toben. Gib Dir daf\u00fcr einen gewissen Zeitraum, denn das seit Jahrzehnten propagierte ausnahmslos positive Denken bringt einen einfach nicht weiter in diesen Situationen. Das ist reine Verdr\u00e4ngung! Kennst Du S\u00e4tze wie: &#8222;Hey, es gibt doch gar keine Probleme, es gibt nur Herausforderungen!&#8220; AAAAAAHHHHH! Bei solchen S\u00e4tzen k\u00f6nnte ich kotzen! Sowas sagen nur Menschen, die ganz offensichtlich noch nie ein echtes fettes Problem in ihrem Leben hatten, sonst w\u00fcrden sie nicht so einen Mist von sich geben.<\/p>\n<p>Fakt ist: Manchmal sind Probleme einfach nur Probleme. Sie f\u00fchlen sich an wie Probleme, sie wirken sich aus wie Probleme und sie sind verdammt nochmal auch einfach Probleme! Wo ist das Problem daran, das Wort &#8222;Problem&#8220; auszusprechen? Probleme werden nicht deswegen kleiner, nur weil ich das Wort aus meinem Wortschatz streiche und es gegen ein anderes Wort ersetze! Das Problem ist doch gar nicht, dass wir Probleme haben. Unser Problem ist vielmehr, dass wir glauben keine Probleme haben zu d\u00fcrfen und dass wir nicht wissen, wie wir mit den Gef\u00fchlen umgehen sollen, die durch unsere Probleme entstehen.<\/p>\n<p>Wie geht man mit diesen Tiefs im Leben also sinnvoll um? Entscheidend ist wie gesagt erstmal, dass Du in diesen Situationen Deine Gef\u00fchle nicht verdr\u00e4ngst, sondern in gewissen Rahmen zul\u00e4sst und zugleich aber auch die Kontrolle \u00fcber diese Gef\u00fchle beh\u00e4ltst. WICHTIG: Du musst <strong>bewusst<\/strong> entscheiden, <strong>wann und wie<\/strong> Du Deine Wut, Deinen Frust, Deinen \u00c4rger oder Deine Trauer rausl\u00e4sst, und wann eben nicht. Alles im Leben hat seine Zeit, auch das Negative! Diese Zeit d\u00fcrfen sich jedoch keinesfalls Deine Gef\u00fchle NEHMEN, sondern diese Zeit GIBST Du ihnen. Du bist und bleibst der Chef \u00fcber Deine Gef\u00fchle! Denn wenn Du Gef\u00fchle hast, ist das okay, ganz gleich welche Gef\u00fchle es sind. Wenn die Gef\u00fchle jedoch Dich haben, dann wird es wirklich problematisch, da Du die Kontrolle verlierst \u00fcber Dein Seelenleben.<\/p>\n<p>Bleibe daher in der Kontrolle und gib Deinen Emotionen den entsprechenden Freiraum, den Du ZEITLICH definierst. Nat\u00fcrlich darfst Du weinen, ja auch laut. Du darfst auch schreien, ein Buch gegen die Wand feuern oder einfach nur mit leerem Blick auf der Couch sitzen und traurig sein. All das ist f\u00fcr einen gewissen Zeitraum okay. Doch DU BESTIMMST, wann dieser Zeitraum anf\u00e4ngt und wann er eben auch wieder aufh\u00f6rt.<\/p>\n<p><strong>Gef\u00fchls-Management &#8211; Den Fokus wieder neu ausrichten<\/strong><\/p>\n<p>Wenn Du Deinen Emotionen freien Lauf gelassen hast, bekommt Dein Kopf wieder die M\u00f6glichkeit, klarer zu denken. Und dann mache Dir bitte eine Sache bewusst: ALLES IM LEBEN, TR\u00c4GT ETWAS GUTES IN SICH!<br \/>\nIch gebe durchaus zu: Manchmal ist dieses &#8222;Gute&#8220; sehr sehr gut versteckt. Und in der Situation des Schmerzes ist es auch nicht immer gleich erkennbar, was da nun Gutes an der Sache sein soll. Doch nach dem Gesetz der Polarit\u00e4t ist es zwingend so, dass neben jedem tiefen Tal automatisch auch ein gro\u00dfer hoher Berg stehen MUSS &#8211; ansonsten g\u00e4be es das Tal nicht. Schicksalsschl\u00e4ge, Lebenskrisen, tiefe Entt\u00e4uschungen oder Probleme sind nichts anderes als T\u00e4ler, die Wendepunkte in Deinem Leben sind.<\/p>\n<p>Es sind Umkehrpunkte, die Dich wieder auf den n\u00e4chsten Berg mit toller Aussicht und gro\u00dfartigen Gef\u00fchlen leiten, vorausgesetzt Du gehst auch weiter und bleibst nicht auf Dauer im Tal sitzen und bemitleidest Dich, und schimpfst \u00fcber Dein j\u00e4mmerliches Schicksal und die Ungerechtikeit der Welt. Jedes pers\u00f6nliche Tief ist ein Hinweis des Lebens, dass es nun f\u00fcr Dich an der Zeit ist zu wachsen und Dich weiterzuentwickeln. Denn: DORT WO DEIN GR\u00d6SSTER SCHMERZ, DEINE GR\u00d6SSTE ANGST UND DEIN GR\u00d6SSTES PROBLEM LIEGT, DORT LIEGT AUCH DEIN GR\u00d6SSTES ENTWICKLUNGSPOTENZIAL!<\/p>\n<p>Schau zur\u00fcck in Dein Leben: Es gibt NICHTS, aber wirklich \u00fcberhaupt nichts, was Du heute kannst, gelernt oder erreicht hast, wof\u00fcr Du keine R\u00fcckschl\u00e4ge oder Probleme \u00fcberwinden musstest. Stimmts? Alles was Du heute wei\u00dft oder kannst, hast Du gelernt, weil Du unz\u00e4hlig viele teils kleine, teils auch gro\u00dfe Probleme und Schwierigkeiten \u00fcberwunden hast. Es gab viele R\u00fcckschl\u00e4ge, Schmerzen, Entt\u00e4uschungen usw., doch Du hast sie \u00fcberwunden und heute bist Du dadurch ein st\u00e4rkerer Mensch, also vor diesen Problemen.<\/p>\n<p>Nimm doch einmal ein gr\u00f6\u00dferes Problem aus Deiner Vergangenheit, das Du bereits gel\u00f6st oder zumindest \u00fcberwunden hast. Komm schon, lies den Text hier nicht nur runter, sondern mach AKTIV mit! Nur so bringt Dir das Ganze auch etwas!<br \/>\nAlso: W\u00e4hle ein Problem aus Deiner Vergangenheit aus &#8211; entscheide Dich f\u00fcr einen konkreten Vorfall.<br \/>\nNun frage Dich: Was kann ich heute, weil ich dieses Problem damals hatte? Was habe ich dadurch gelernt? Wie hat es mich besser gemacht? Wie bin ich dadurch st\u00e4rker geworden oder wie war ich gezwungen dadurch st\u00e4rker zu werden? Welche Entscheidungen habe ich damals deswegen getroffen und wo stehe ich heute, weil ich diese Entscheidung damals getroffen habe? Welche Menschen habe ich kennengelernt? Wie bin ich als Mensch st\u00e4rker, reifer, erfahrener und robuster geworden, weil es dieses Problem damals gab? Nimm Dir gerne ein Blatt Papier und schreibe Dir Deine Antworten auf. Nimm Dir daf\u00fcr gerne etwas Zeit &#8211; also ich meine mehr Zeit als 1 Minute.<\/p>\n<p>Du wirst merken: Im R\u00fcckblick betrachtet, haben Dich all Deine Probleme, R\u00fccksckschl\u00e4ge und Krisen im Leben auf gewisse Weise st\u00e4rker gemacht. Das bedeutet nicht, dass Du das gleiche Problem gerne nochmal h\u00e4ttest, nein! Aber es bedeutet, dass es IMMER etwas Gutes in ALLEM gibt. Man versteht es oft erstmal nicht, was das Gute sein soll, wenn man gerade akut in dieser schmerzhaften Situation steckt. Doch das \u00e4ndert nichts daran, dass der positive Aspekt, wenn auch versteckt, dennoch vorhanden ist. Merke Dir: DAS GUTE AN DEN DINGEN IM LEBEN VERSTEHT MAN MEIST NUR IM R\u00dcCKBLICK. LEBEN MUSST DU DEIN LEBEN ALLERDINGS MIT DEM BLICK NACH VORNE.<\/p>\n<p>Jede Schwierigkeit im Leben bietet Dir die Chance, besser und st\u00e4rker zu werden. Daher m\u00f6chte ich Dir eine Strategie empfehlen, die sich f\u00fcr mich als sehr effektiv erwiesen hat, bei der \u00dcberwindung meiner Probleme und Krisen: GEHE MIT GROSSER NEUGIER DURCH DEN WENDEPUNKT DEINES LEBENS UND SUCHE NACH ASPEKTEN, WIE DICH DIESE SITUATION NUN BESSER MACHEN KANN.<br \/>\nNeugier ist f\u00fcr mich hier der entscheidende Schl\u00fcsselbegriff. Ich spiele hier f\u00fcr mich gerne Potenzialentwicklungs-Detektiv. Ich frage mich stets: Okay, wenn ich dieses Problem jetzt l\u00f6sen oder \u00fcberwinden will, was muss ich dann an mir verbessern? Wie muss ich st\u00e4rker werden? Was muss ich lernen? Wie wird sich diese neue\/verbesserte F\u00e4higkeit dann auf mein Leben auswirken? Wenn ich das geschafft habe, was kann ich dann noch alles (leichter) schaffen?<br \/>\nIch bin st\u00e4ndig neugierig und auf der Suche, wie ich nun durch diese Situation besser werden kann. Darauf geht mein voller Fokus. Ich beobachte mich genau und registriere jede kleine Verbesserung an mir &#8211; schriftlich! Die Herausforderungen des Lebens ist dennoch hart und ich muss den Schmerz ertragen und k\u00e4mpfen, doch mein Fokus liegt nicht beim Problem, bei den Umst\u00e4nden, dem unfairen Leben oder gar dem Moment, wenn das Problem endlich mal \u00fcberwunden ist. Nein, mein Fokus ist einzig und alleine auf meiner per\u00f6nliche Entwicklung gelenkt. Und das gibt ein ziemlich gutes Gef\u00fchl, denn man wird schnell besser, wenn man schwierige Situationen annimmt und Tag f\u00fcr Tag bewusst daran arbeitet, st\u00e4rker zu werden.<\/p>\n<p>Also merke Dir: Es gibt immer und an allem etwas Gutes daran. Es gibt hinter allen Dingen einen tieferen Sinn, auch wenn Du ihn anfangs wom\u00f6glich noch nicht erkennen kannst. Doch wenn Du neugierig bist und bleibst, wirst Du wachsen, Dich entwickeln, st\u00e4rker werden und diese positiven Aspekte eines Tages auch erkennen. Und Du wirst mit Stolz zur\u00fcckschauen und feststellen: Auch dieses Problem hat mich nicht zerbrochen, sondern noch st\u00e4rker gemacht!<br \/>\nGERADE AUCH DIE TIEFSTEN TIEFS SIND DIE VORBOTEN DEINER GR\u00d6SSTEN ERFOLGE UND ENTWICKLUNGSSPR\u00dcNGE IM LEBEN.<\/p>\n<p>Also: Nimm Dir Zeit, ein Blatt Papier und Stift und frage Dich: Was ist das Gute daran, dass&#8230;.<\/p>\n<p>Viel Erfolg dabei w\u00fcnscht Dir Dein<\/p>\n<p>Steffen Kirchner<\/p>\n<p>&nbsp;<\/p>\n<p>P.S.: Vertiefe Dein Wissen \u00fcber dieses Thema und erhalte eine gro\u00dfe Menge neuer Tools und Techniken, um schwierige Lebensphasen und Gef\u00fchlstiefs zu \u00fcberwinden und gest\u00e4rkt daraus hervorzugehen <strong>=&gt; <a href=\"http:\/\/www.lebensstark-seminar.de\">www.lebensstark-seminar.de<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Es gibt mehrere universelle Gesetzm\u00e4\u00dfigkeiten. Eines davon ist das Gesetz der Polarit\u00e4t. Dieses besagt, dass es von allem in der Welt immer zwei Pole geben muss &#8211; Schwarz &amp; Wei\u00df, Licht &amp; Schatten, Plus &amp; Minus, Tag &amp; Nacht etc.. &hellip; <a href=\"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[20,335,1,25,16,23],"tags":[356,42,74,59,553,552,548,551,401,554,549,348,118,550],"class_list":["post-1220","post","type-post","status-publish","format-standard","hentry","category-erfolgsimpulse","category-lebens-stark","category-lebensglueck","category-lebenslektionen","category-motivation","category-spitzenleistung-leben","tag-aktions-element","tag-entwicklung","tag-fokus","tag-geschichte","tag-persoenlichkeit","tag-perspektive","tag-probleme","tag-refraiming","tag-rueckschlaege","tag-schiffbruechige","tag-schwierigkeiten","tag-staerken","tag-wachstum","tag-was-ist-das-gute"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Probleme? Was ist das Gute daran?<\/title>\n<meta name=\"description\" content=\"In diesem Artikel erf\u00e4hrst Du, warum Probleme in Wahrheit Geschenke sind und mit welcher Strategie Du emotionale Tiefs besser \u00fcberwinden kannst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Probleme? Was ist das Gute daran?\" \/>\n<meta property=\"og:description\" content=\"In diesem Artikel erf\u00e4hrst Du, warum Probleme in Wahrheit Geschenke sind und mit welcher Strategie Du emotionale Tiefs besser \u00fcberwinden kannst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen Kirchner Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/steffenkirchner.de\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/de-de.facebook.com\/steffenkirchner.de\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-18T14:08:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-17T11:57:46+00:00\" \/>\n<meta name=\"author\" content=\"Steffen Kirchner\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen Kirchner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/\"},\"author\":{\"name\":\"Steffen Kirchner\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"headline\":\"Probleme? Was ist das Gute daran?\",\"datePublished\":\"2016-08-18T14:08:11+00:00\",\"dateModified\":\"2018-09-17T11:57:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/\"},\"wordCount\":1846,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"keywords\":[\"Aktions-Element\",\"Entwicklung\",\"Fokus\",\"Geschichte\",\"Pers\u00f6nlichkeit\",\"Perspektive\",\"Probleme\",\"Refraiming\",\"R\u00fcckschl\u00e4ge\",\"Schiffbr\u00fcchige\",\"Schwierigkeiten\",\"St\u00e4rken\",\"Wachstum\",\"Was ist das Gute\"],\"articleSection\":[\"Erfolgsimpulse\",\"LEBENS STARK\",\"Lebensgl\u00fcck\",\"Lebenslektionen\",\"Motivation\",\"Spitzenleistung im Leben\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/\",\"name\":\"Probleme? Was ist das Gute daran?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\"},\"datePublished\":\"2016-08-18T14:08:11+00:00\",\"dateModified\":\"2018-09-17T11:57:46+00:00\",\"description\":\"In diesem Artikel erf\u00e4hrst Du, warum Probleme in Wahrheit Geschenke sind und mit welcher Strategie Du emotionale Tiefs besser \u00fcberwinden kannst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/gutes-an-problemen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Probleme? Was ist das Gute daran?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\",\"name\":\"Steffen Kirchner Blog\",\"description\":\"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\",\"name\":\"Steffen Kirchner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"caption\":\"Steffen Kirchner\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.steffenkirchner.de\",\"https:\\\/\\\/de-de.facebook.com\\\/steffenkirchner.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/steffen.kirchner\\\/channel\\\/?hl=de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/steffen-kirchner\\\/?originalSubdomain=de\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZVCBY3k27CCmKxMNzLtedA\"],\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/author\\\/admin\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Probleme? Was ist das Gute daran?","description":"In diesem Artikel erf\u00e4hrst Du, warum Probleme in Wahrheit Geschenke sind und mit welcher Strategie Du emotionale Tiefs besser \u00fcberwinden kannst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/","og_locale":"de_DE","og_type":"article","og_title":"Probleme? Was ist das Gute daran?","og_description":"In diesem Artikel erf\u00e4hrst Du, warum Probleme in Wahrheit Geschenke sind und mit welcher Strategie Du emotionale Tiefs besser \u00fcberwinden kannst.","og_url":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/","og_site_name":"Steffen Kirchner Blog","article_publisher":"https:\/\/de-de.facebook.com\/steffenkirchner.de\/","article_author":"https:\/\/de-de.facebook.com\/steffenkirchner.de\/","article_published_time":"2016-08-18T14:08:11+00:00","article_modified_time":"2018-09-17T11:57:46+00:00","author":"Steffen Kirchner","twitter_misc":{"Verfasst von":"Steffen Kirchner","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/#article","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/"},"author":{"name":"Steffen Kirchner","@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"headline":"Probleme? Was ist das Gute daran?","datePublished":"2016-08-18T14:08:11+00:00","dateModified":"2018-09-17T11:57:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/"},"wordCount":1846,"commentCount":2,"publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"keywords":["Aktions-Element","Entwicklung","Fokus","Geschichte","Pers\u00f6nlichkeit","Perspektive","Probleme","Refraiming","R\u00fcckschl\u00e4ge","Schiffbr\u00fcchige","Schwierigkeiten","St\u00e4rken","Wachstum","Was ist das Gute"],"articleSection":["Erfolgsimpulse","LEBENS STARK","Lebensgl\u00fcck","Lebenslektionen","Motivation","Spitzenleistung im Leben"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/","url":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/","name":"Probleme? Was ist das Gute daran?","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#website"},"datePublished":"2016-08-18T14:08:11+00:00","dateModified":"2018-09-17T11:57:46+00:00","description":"In diesem Artikel erf\u00e4hrst Du, warum Probleme in Wahrheit Geschenke sind und mit welcher Strategie Du emotionale Tiefs besser \u00fcberwinden kannst.","breadcrumb":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.steffenkirchner.de\/blog\/gutes-an-problemen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.steffenkirchner.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Probleme? Was ist das Gute daran?"}]},{"@type":"WebSite","@id":"https:\/\/www.steffenkirchner.de\/blog\/#website","url":"https:\/\/www.steffenkirchner.de\/blog\/","name":"Steffen Kirchner Blog","description":"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner","publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.steffenkirchner.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4","name":"Steffen Kirchner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","caption":"Steffen Kirchner"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.steffenkirchner.de","https:\/\/de-de.facebook.com\/steffenkirchner.de\/","https:\/\/www.instagram.com\/steffen.kirchner\/channel\/?hl=de","https:\/\/www.linkedin.com\/in\/steffen-kirchner\/?originalSubdomain=de","https:\/\/www.youtube.com\/channel\/UCZVCBY3k27CCmKxMNzLtedA"],"url":"https:\/\/www.steffenkirchner.de\/blog\/author\/admin\/"},false]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4QCGC-jG","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/1220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/comments?post=1220"}],"version-history":[{"count":9,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/1220\/revisions"}],"predecessor-version":[{"id":1229,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/1220\/revisions\/1229"}],"wp:attachment":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/media?parent=1220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/categories?post=1220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/tags?post=1220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}