{"id":628,"date":"2014-02-21T23:32:46","date_gmt":"2014-02-21T22:32:46","guid":{"rendered":"http:\/\/www.steffenkirchner.de\/blog\/?p=628"},"modified":"2014-02-22T00:06:40","modified_gmt":"2014-02-21T23:06:40","slug":"die-groessten-ausreden-teil-1-zeitmangel","status":"publish","type":"post","link":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/","title":{"rendered":"Unsere beliebtesten Ausreden &#8211; Teil 1: Zeitmangel"},"content":{"rendered":"<p>Zeitmangel ist des Deutschen liebestes Ausreden-Kind. S\u00e4tze wie<em> &#8222;Daf\u00fcr habe ich keine Zeit&#8220;<\/em>, oder<em> &#8222;Das dauert mir zu lange. Das mache ich mal wenn ich die Mu\u00dfe daf\u00fcr habe&#8220;<\/em>, sind sicherlich jedem bekannt. Zeitmangel ist schon seit vielen Jahren die Allzweckwaffe und das Totschlagargument schlecht hin, um Ver\u00e4nderungen und Weiterentwicklung zu verhindern. Lassen Sie uns heute mal genauer hinschauen, was hinter dieser Ausrede in Wirklichkeit steckt.<!--more--><\/p>\n<p><em>&#8222;Ich habe jetzt keine Zeit&#8220;<\/em> &#8211; wie oft haben Sie diesen Satz heuer schon geh\u00f6rt oder vielleicht auch selbst gesagt? Unter Zeitmangel oder Stress zu leiden ist heutzutage fast schon ein Statussymbol. Wer keinen Stress hat, der arbeitet nicht oder hat offensichtlich keinen anspruchsvollen Job. Was f\u00fcr ein dummer Aberglaube! Diese Fehlhaltung unserer Multi-Tasking-Gesellschaft verschlimmerte sich vor allem in den letzten 10-15 Jahren ganz massiv. Schon l\u00e4ngst sind wir z.B. auch nicht mehr Herr der ganzen technischen Neuentwicklungen, die uns eigentlich als Hilfsmittel dienen sollten um Zeit zu sparen. Anstatt dessen sind wir zu Sklaven der Technik geworden und lassen uns von ihr diktieren. Wer kennt nicht das pausenlose Gebimmel von Erinnerungst\u00f6nen am Handy, die einen unnachgiebig dazu antreiben, endlich zum n\u00e4chsten Termin aufzubrechen, zu dem man eigentlich schon vor 10 Minuten h\u00e4tte losfahren sollen. Das vertraute Gespr\u00e4ch mit dem gegen\u00fcbersitzenden Menschen wird abgebrochen. Eigentlich w\u00e4re es noch sch\u00f6n und wichtig, weiterzusprechen. Aber das Handy belehrt uns dar\u00fcber, was nun auf der Tagesordnung steht: 13.15 Uhr &#8211; Projektgruppen Meeting. Also los los.<\/p>\n<p>K\u00fcrzlich las ich einen sch\u00f6nen Spruch:<em> &#8222;Als Gott die Welt erschuf, gab er den Afrikanern die Zeit und den Europ\u00e4ern die Uhr.&#8220;\u00a0<\/em>Das bringt es auf den Punkt. Zeitmangel ist kein menschliches sondern ein gesellschaftliches Problem. Wir haben verlernt zu unterscheiden zwischen Dringendem und Wichtigem. Wir versuchen unsere Zeit zu optimieren, anstatt sie zu nutzen. Schreiben Sie sich doch jetzt grade mal alle <strong>dringenden Aufgaben<\/strong> auf, die Sie heute oder in den n\u00e4chsten paar Tagen unbedingt zu erledigen haben. Und dann schreiben Sie sich daneben alle wirklich <strong>wichtigen Dinge<\/strong> auf, die Sie unbedingt gerne mal tun w\u00fcrden, wenn die Zeit daf\u00fcr nur da w\u00e4re.<br \/>\nF\u00e4llt Ihnen was auf? Dringendes machen wir meist f\u00fcr andere, Wichtiges w\u00e4re oft f\u00fcr uns selbst. Den Sohn zum Training fahren und wieder abholen, das Protokoll f\u00fcr den Verein fertigstellen, dem Chef die Dokumentation vorbereiten, f\u00fcr die Familie kochen, den Anzug des Ehemannes in die Reinigung bringen und nat\u00fcrlich auch noch die f\u00fcnf Kunden zur\u00fcckrufen, die auf neue Updates warten.<\/p>\n<p>Verstehen Sie mich bitte richtig: An diesen dringenden Aufgaben ist nichts negativ. Sie sind aber eben ausschlie\u00dflich nur daf\u00fcr da, um die Erwartungen und W\u00fcnsche anderer Menschen zu erf\u00fcllen. Doch was ist mit Ihrem Yoga-Kurs, den Sie schon lange machen wollten? Was ist mit der Tennisstunde die Sie mit Ihrem Kumpel schon seit sechs Monaten von Mal zu Mal verschieben? Was ist mit dem neuen Buch, das Sie vor f\u00fcnf Wochen so begeistert und voller Vorfreude gekauft haben und das seitdem aber immer noch ungelesen auf Ihrem Nachtk\u00e4stchen liegt? Was ist mit dem zweiw\u00f6chigen Traumurlaub am Strand, den Sie sich schon seit Jahren planen ohne ihn zu buchen? Und was ist eigentlich mit all Ihren Freunden und Bekannten, die Sie fr\u00fcher jede Woche getroffen haben und es jetzt keine f\u00fcnf Mal im Jahr mehr schaffen, weil eben keine Zeit daf\u00fcr da ist?! Ist das alles wirklich ein Beweis f\u00fcr Zeitmangel, oder nicht eher ein Beweis daf\u00fcr, dass man ehrlich gesagt falsch lebt und die Verantwortung f\u00fcr die eigenen Bed\u00fcrfnisse an die &#8222;dringende Erwartungen&#8220; von au\u00dfen abgegeben hat?<\/p>\n<p><strong>Zeitmangel ad\u00e9 &#8211; Was &#8222;Ich habe keine Zeit&#8220; in Wirklichkeit hei\u00dft<\/strong><\/p>\n<p><strong> 1.: Zeitmangel gibt es nicht. Priorit\u00e4tenmangel daf\u00fcr umso mehr<\/strong>.<br \/>\nKeine Zeit f\u00fcr etwas zu haben, ist nichts anderes als eine verschl\u00fcsselte Botschaft f\u00fcr die Wahrheit: <em>&#8222;Es ist mir nicht wichtig genug.&#8220; <\/em>Nehmen wir doch mal ein Beispiel: Manche Leute kommen zu mir und sagen:<em> &#8222;Ich w\u00fcrde so gerne an Ihrer Seminarwoche, den Inspirationstagen, teilnehmen. Aber ich habe da einfach keine Zeit.&#8220;<\/em> Was w\u00e4re, wenn ich diesen Personen schriftlich garantieren w\u00fcrde, dass Sie 100.000 Euro geschenkt bekommen, wenn sie k\u00e4men? Jeder w\u00fcrde sagen:<em> &#8222;Okay, dann komme ich doch. Wo muss ich unterschreiben?&#8220;<\/em><\/p>\n<p>Keine Zeit zu haben ist<strong> immer<\/strong> eine Ausrede. Menschen haben nicht &#8222;keine Zeit&#8220;, sondern keine klaren Priorit\u00e4ten. Jeder Mensch hat t\u00e4glich 24 Stunden Zeit. Es gibt keinen Zeitmangel. Denn es ist ja auch Zeit f\u00fcr die Daily Soap, das st\u00e4ndige Facebooken und Email-checken, SMS schreiben, die Autopflege, das Fu\u00dfballwochenende mit den Kumpels, die Raucherpausen im B\u00fcro usw.. Die Frage ist also nicht:<em> &#8222;Haben Sie daf\u00fcr Zeit?&#8220;<\/em>, sondern:<em> &#8222;Ist es Ihnen wichtig genug?&#8220;<\/em><br \/>\nWenn Sie mit jemandem sprechen wollen und der Ihnen zum wiederholten Male sagt, dass er daf\u00fcr jetzt leider keine Zeit hat, dann k\u00f6nnen Sie mit absoluter Sicherheit davon ausgehen, dass Sie bzw. das gemeinsame Gespr\u00e4ch, dieser Person nicht besonders wichtig ist. In der Priorit\u00e4tenliste dieses Menschen sind Sie ganz einfach unter den Top 10 &#8211; Punkt aus. Die Konsequenzen die Sie daraus ziehen, m\u00fcssen Sie selbst entscheiden. Entweder Sie machen denjenigen auf seine mangelhaften Priorit\u00e4ten aufmerksam, oder Sie haken den Kontakt ab. Denn Sie sollten sich nicht f\u00fcr Menschen interessieren, die kein Interesse an Ihnen haben.<\/p>\n<p><strong> 2.: Chronischer Zeitmangel entsteht durch Bequemlichkeit<br \/>\n<\/strong>Auch wenn es sich vielleicht im ersten Moment komisch anh\u00f6rt, aber die Wahrheit lautet: Wer dauerhaft (!) unter Zeitmangel und Stress leidet, hat dies durch seine eigene Faulheit bzw. Bequemlichkeit verursacht. Warum? Weil es ein Leichtes ist, seine Zeit zu verplanen und seinen Terminkalender von morgens bis abends zu f\u00fcllen. Sehr viel anspruchsvoller ist es, klare Priorit\u00e4ten zu setzen, den Termin- und Aufgabendschungel klar zu strukturieren, zu vereinfachen und f\u00fcr Zeitpolster zu sorgen. Wer einigerma\u00dfen ambitionierte Ziele im Leben hat, muss sich mit Sicherheit nicht anstrengen, um von morgens bis abends unterwegs sein zu k\u00f6nnen. Langweilig wird es nur Menschen ohne Ziel und Plan im Leben.<br \/>\nDoch nur diejenigen, die mit Flei\u00df und Engagement ihren gut gef\u00fcllten Terminkalender bereinigen bzw. entschleunigen, versinken auf Dauer gesehen nicht in Chaos und Hektik. Stress zu haben ist keine Kunst &#8211; das schaffen auch Faultiere. Stress zu vermeiden und Zeit f\u00fcr das Wichtige anstatt nur f\u00fcr das Dringende zu haben, beweist Flei\u00df, \u00dcbersicht und Weitblick.<\/p>\n<p>Wer stets so gut wie keine Zeit hat, offenbart lediglich seine fehlende Verantwortung f\u00fcr sich selbst oder seine fehlende Wertsch\u00e4tzung f\u00fcr das Wichtige (oder die wichtigen Menschen) im Leben. Wer sich Zeit nimmt, beweist hingegen wahre Gr\u00f6\u00dfe, klares Wertebewusstsein und Organisationstalent. F\u00fcr ein gl\u00fcckliches und gesundes Leben ist dies die Basis. Denn wie sagte Sebastian Kneipp schon seinerzeit: <em>\u201eWer sich heute keine Zeit f\u00fcr seine Gesundheit nimmt, wird sich sp\u00e4ter sehr viel Zeit f\u00fcr seine Krankheiten nehmen m\u00fcssen\u201c<\/em>.<em> <\/em><i><br \/>\n<\/i>Was ist Ihnen also wirklich wichtig? Entscheiden Sie sich jetzt neu!<\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Zeitmangel ist des Deutschen liebestes Ausreden-Kind. S\u00e4tze wie &#8222;Daf\u00fcr habe ich keine Zeit&#8220;, oder &#8222;Das dauert mir zu lange. Das mache ich mal wenn ich die Mu\u00dfe daf\u00fcr habe&#8220;, sind sicherlich jedem bekannt. Zeitmangel ist schon seit vielen Jahren die &hellip; <a href=\"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[20,1,25],"tags":[289,274,27,288],"class_list":["post-628","post","type-post","status-publish","format-standard","hentry","category-erfolgsimpulse","category-lebensglueck","category-lebenslektionen","tag-ausrede","tag-stress","tag-zeit","tag-zeitmangel"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":7,"sum_votes":30},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsere beliebtesten Ausreden - Teil 1: Zeitmangel<\/title>\n<meta name=\"description\" content=\"Zeitmangel und Stress sind kein Zeichen von Flei\u00df, sondern von Faulheit. Steffen Kirchner erkl\u00e4rt , was hinter der Ausrede &quot;Keine Zeit&quot; in Wahrheit steckt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsere beliebtesten Ausreden - Teil 1: Zeitmangel\" \/>\n<meta property=\"og:description\" content=\"Zeitmangel und Stress sind kein Zeichen von Flei\u00df, sondern von Faulheit. Steffen Kirchner erkl\u00e4rt , was hinter der Ausrede &quot;Keine Zeit&quot; in Wahrheit steckt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen Kirchner Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/steffenkirchner.de\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/de-de.facebook.com\/steffenkirchner.de\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-21T22:32:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-21T23:06:40+00:00\" \/>\n<meta name=\"author\" content=\"Steffen Kirchner\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen Kirchner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/\"},\"author\":{\"name\":\"Steffen Kirchner\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"headline\":\"Unsere beliebtesten Ausreden &#8211; Teil 1: Zeitmangel\",\"datePublished\":\"2014-02-21T22:32:46+00:00\",\"dateModified\":\"2014-02-21T23:06:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/\"},\"wordCount\":1195,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"keywords\":[\"Ausrede\",\"Stress\",\"Zeit\",\"Zeitmangel\"],\"articleSection\":[\"Erfolgsimpulse\",\"Lebensgl\u00fcck\",\"Lebenslektionen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/\",\"name\":\"Unsere beliebtesten Ausreden - Teil 1: Zeitmangel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\"},\"datePublished\":\"2014-02-21T22:32:46+00:00\",\"dateModified\":\"2014-02-21T23:06:40+00:00\",\"description\":\"Zeitmangel und Stress sind kein Zeichen von Flei\u00df, sondern von Faulheit. Steffen Kirchner erkl\u00e4rt , was hinter der Ausrede \\\"Keine Zeit\\\" in Wahrheit steckt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/die-groessten-ausreden-teil-1-zeitmangel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere beliebtesten Ausreden &#8211; Teil 1: Zeitmangel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\",\"name\":\"Steffen Kirchner Blog\",\"description\":\"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\",\"name\":\"Steffen Kirchner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"caption\":\"Steffen Kirchner\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.steffenkirchner.de\",\"https:\\\/\\\/de-de.facebook.com\\\/steffenkirchner.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/steffen.kirchner\\\/channel\\\/?hl=de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/steffen-kirchner\\\/?originalSubdomain=de\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZVCBY3k27CCmKxMNzLtedA\"],\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/author\\\/admin\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsere beliebtesten Ausreden - Teil 1: Zeitmangel","description":"Zeitmangel und Stress sind kein Zeichen von Flei\u00df, sondern von Faulheit. Steffen Kirchner erkl\u00e4rt , was hinter der Ausrede \"Keine Zeit\" in Wahrheit steckt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/","og_locale":"de_DE","og_type":"article","og_title":"Unsere beliebtesten Ausreden - Teil 1: Zeitmangel","og_description":"Zeitmangel und Stress sind kein Zeichen von Flei\u00df, sondern von Faulheit. Steffen Kirchner erkl\u00e4rt , was hinter der Ausrede \"Keine Zeit\" in Wahrheit steckt.","og_url":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/","og_site_name":"Steffen Kirchner Blog","article_publisher":"https:\/\/de-de.facebook.com\/steffenkirchner.de\/","article_author":"https:\/\/de-de.facebook.com\/steffenkirchner.de\/","article_published_time":"2014-02-21T22:32:46+00:00","article_modified_time":"2014-02-21T23:06:40+00:00","author":"Steffen Kirchner","twitter_misc":{"Verfasst von":"Steffen Kirchner","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/#article","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/"},"author":{"name":"Steffen Kirchner","@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"headline":"Unsere beliebtesten Ausreden &#8211; Teil 1: Zeitmangel","datePublished":"2014-02-21T22:32:46+00:00","dateModified":"2014-02-21T23:06:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/"},"wordCount":1195,"commentCount":2,"publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"keywords":["Ausrede","Stress","Zeit","Zeitmangel"],"articleSection":["Erfolgsimpulse","Lebensgl\u00fcck","Lebenslektionen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/","url":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/","name":"Unsere beliebtesten Ausreden - Teil 1: Zeitmangel","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#website"},"datePublished":"2014-02-21T22:32:46+00:00","dateModified":"2014-02-21T23:06:40+00:00","description":"Zeitmangel und Stress sind kein Zeichen von Flei\u00df, sondern von Faulheit. Steffen Kirchner erkl\u00e4rt , was hinter der Ausrede \"Keine Zeit\" in Wahrheit steckt.","breadcrumb":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.steffenkirchner.de\/blog\/die-groessten-ausreden-teil-1-zeitmangel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.steffenkirchner.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Unsere beliebtesten Ausreden &#8211; Teil 1: Zeitmangel"}]},{"@type":"WebSite","@id":"https:\/\/www.steffenkirchner.de\/blog\/#website","url":"https:\/\/www.steffenkirchner.de\/blog\/","name":"Steffen Kirchner Blog","description":"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner","publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.steffenkirchner.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4","name":"Steffen Kirchner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","caption":"Steffen Kirchner"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.steffenkirchner.de","https:\/\/de-de.facebook.com\/steffenkirchner.de\/","https:\/\/www.instagram.com\/steffen.kirchner\/channel\/?hl=de","https:\/\/www.linkedin.com\/in\/steffen-kirchner\/?originalSubdomain=de","https:\/\/www.youtube.com\/channel\/UCZVCBY3k27CCmKxMNzLtedA"],"url":"https:\/\/www.steffenkirchner.de\/blog\/author\/admin\/"},false]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4QCGC-a8","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/comments?post=628"}],"version-history":[{"count":25,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/628\/revisions"}],"predecessor-version":[{"id":653,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/628\/revisions\/653"}],"wp:attachment":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/media?parent=628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/categories?post=628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/tags?post=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}