{"id":729,"date":"2014-07-13T17:23:52","date_gmt":"2014-07-13T15:23:52","guid":{"rendered":"http:\/\/www.steffenkirchner.de\/blog\/?p=729"},"modified":"2018-09-17T15:55:07","modified_gmt":"2018-09-17T13:55:07","slug":"spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner","status":"publish","type":"post","link":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/","title":{"rendered":"Spezialausgabe: 30-min\u00fctiges Podcast-Interview mit Steffen Kirchner"},"content":{"rendered":"<div id=\"attachment_731\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-731\" class=\"size-full wp-image-731\" src=\"http:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime.jpg\" alt=\"Steffen Kirchner war zu Gast in TomsTalkTime, dem Erfolgspodcast\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime.jpg 300w, https:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-731\" class=\"wp-caption-text\">Steffen Kirchner war zu Gast in TomsTalkTime, dem Erfolgspodcast<\/p><\/div>\n<p>Obwohl Sie es hier an dieser Stelle gewohnt sind, Inhalte von mir zu <strong>lesen<\/strong>, d\u00fcrfen Sie heute im Rahmen eines tollen Podcast-Interviews einige Impulse von mir <strong>h\u00f6ren<\/strong>. <!--more--><\/p>\n<p>Anfang Juli war ich als Interviewpartner zu Gast beim bekannten Erfolgspodcast <a href=\"http:\/\/tomstalktime.com\/\" target=\"_blank\" rel=\"noopener\">TomsTalkTime.com<\/a>. TomsTalkTime ist eine deutschsprachige Business-Podcast-Show mit internationalem Top Ranking, die von Tom Kaules produziert und moderiert wird. Dreimal mal pro Woche inspiriert Tom seine Zuh\u00f6rer, welche den Podcast mittlerweile in \u00fcber 90 L\u00e4ndern h\u00f6ren.<\/p>\n<p>Das Ziel des Erfolgspodcast TomsTalkTime ist es, die Prinzipien des Erfolgs zu verstehen und zu erlernen. Inspirierende Interviews und Storys von erfolgreichen Unternehmern und Prominenten, verraten immer wieder neue Erfolgsstrategien. Durch die Experten-Interviews erf\u00e4hrt man, wie erfolgreiche Menschen erfolgreich geworden sind und noch wichtiger: warum sie erfolgreich bleiben.<\/p>\n<p>Genie\u00dfen Sie das 30-min\u00fctige Interview mit mir auf TomsTalkTime, in dem ich \u00fcber eigene gro\u00dfe Fehler, pers\u00f6nliche Erfolgsstrategien, Aha-Momente und wertvolle Businesstipps spreche, die ich aus meiner Erfahrung jedem Menschen empfehlen kann, der sich selbst\u00e4ndig machen will.<\/p>\n<p><strong><a href=\"http:\/\/tomstalktime.com\/265-steffen-kirchner-speaker-und-mentalcoach-auf-hochstem-niveau\/\" target=\"_blank\" rel=\"noopener\">Hier k\u00f6nnen Sie den Podcast anh\u00f6ren.<\/a><\/strong><\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Obwohl Sie es hier an dieser Stelle gewohnt sind, Inhalte von mir zu lesen, d\u00fcrfen Sie heute im Rahmen eines tollen Podcast-Interviews einige Impulse von mir h\u00f6ren.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[20,21,1,25,16,26,22,23,24],"tags":[329,328,331,330],"class_list":["post-729","post","type-post","status-publish","format-standard","hentry","category-erfolgsimpulse","category-erfolgsstorys","category-lebensglueck","category-lebenslektionen","category-motivation","category-erlebnisse","category-spitzenleistung-beruf","category-spitzenleistung-leben","category-verblueffend-faszinierend","tag-interview","tag-podcast","tag-tom-kaules","tag-tomstalktime"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":1,"sum_votes":4},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>30-min\u00fctiges Podcast-Interview mit Steffen Kirchner<\/title>\n<meta name=\"description\" content=\"In diesem 30-min\u00fctigen Podcast-Interview spricht Steffen Kirchner \u00fcber seine gr\u00f6\u00dften Fehler, Erfolgsstrategien, Aha-Momente und Businesstipps. Viel Spa\u00df!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30-min\u00fctiges Podcast-Interview mit Steffen Kirchner\" \/>\n<meta property=\"og:description\" content=\"In diesem 30-min\u00fctigen Podcast-Interview spricht Steffen Kirchner \u00fcber seine gr\u00f6\u00dften Fehler, Erfolgsstrategien, Aha-Momente und Businesstipps. Viel Spa\u00df!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen Kirchner Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/steffenkirchner.de\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/de-de.facebook.com\/steffenkirchner.de\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-13T15:23:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-17T13:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime.jpg\" \/>\n<meta name=\"author\" content=\"Steffen Kirchner\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steffen Kirchner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/\"},\"author\":{\"name\":\"Steffen Kirchner\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"headline\":\"Spezialausgabe: 30-min\u00fctiges Podcast-Interview mit Steffen Kirchner\",\"datePublished\":\"2014-07-13T15:23:52+00:00\",\"dateModified\":\"2018-09-17T13:55:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/\"},\"wordCount\":200,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"image\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/tomstalktime.jpg\",\"keywords\":[\"Interview\",\"Podcast\",\"Tom Kaules\",\"TomsTalkTime\"],\"articleSection\":[\"Erfolgsimpulse\",\"Erfolgsstorys\",\"Lebensgl\u00fcck\",\"Lebenslektionen\",\"Motivation\",\"Pers\u00f6nliche Erlebnisse\",\"Spitzenleistung im Beruf\",\"Spitzenleistung im Leben\",\"Verbl\u00fcffendes &amp; Faszinierendes\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/\",\"name\":\"30-min\u00fctiges Podcast-Interview mit Steffen Kirchner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/tomstalktime.jpg\",\"datePublished\":\"2014-07-13T15:23:52+00:00\",\"dateModified\":\"2018-09-17T13:55:07+00:00\",\"description\":\"In diesem 30-min\u00fctigen Podcast-Interview spricht Steffen Kirchner \u00fcber seine gr\u00f6\u00dften Fehler, Erfolgsstrategien, Aha-Momente und Businesstipps. Viel Spa\u00df!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/tomstalktime.jpg\",\"contentUrl\":\"http:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/tomstalktime.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spezialausgabe: 30-min\u00fctiges Podcast-Interview mit Steffen Kirchner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\",\"name\":\"Steffen Kirchner Blog\",\"description\":\"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\",\"name\":\"Steffen Kirchner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"caption\":\"Steffen Kirchner\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.steffenkirchner.de\",\"https:\\\/\\\/de-de.facebook.com\\\/steffenkirchner.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/steffen.kirchner\\\/channel\\\/?hl=de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/steffen-kirchner\\\/?originalSubdomain=de\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZVCBY3k27CCmKxMNzLtedA\"],\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/author\\\/admin\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"30-min\u00fctiges Podcast-Interview mit Steffen Kirchner","description":"In diesem 30-min\u00fctigen Podcast-Interview spricht Steffen Kirchner \u00fcber seine gr\u00f6\u00dften Fehler, Erfolgsstrategien, Aha-Momente und Businesstipps. Viel Spa\u00df!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/","og_locale":"de_DE","og_type":"article","og_title":"30-min\u00fctiges Podcast-Interview mit Steffen Kirchner","og_description":"In diesem 30-min\u00fctigen Podcast-Interview spricht Steffen Kirchner \u00fcber seine gr\u00f6\u00dften Fehler, Erfolgsstrategien, Aha-Momente und Businesstipps. Viel Spa\u00df!","og_url":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/","og_site_name":"Steffen Kirchner Blog","article_publisher":"https:\/\/de-de.facebook.com\/steffenkirchner.de\/","article_author":"https:\/\/de-de.facebook.com\/steffenkirchner.de\/","article_published_time":"2014-07-13T15:23:52+00:00","article_modified_time":"2018-09-17T13:55:07+00:00","og_image":[{"url":"http:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime.jpg","type":"","width":"","height":""}],"author":"Steffen Kirchner","twitter_misc":{"Verfasst von":"Steffen Kirchner","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/#article","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/"},"author":{"name":"Steffen Kirchner","@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"headline":"Spezialausgabe: 30-min\u00fctiges Podcast-Interview mit Steffen Kirchner","datePublished":"2014-07-13T15:23:52+00:00","dateModified":"2018-09-17T13:55:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/"},"wordCount":200,"commentCount":0,"publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"image":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/#primaryimage"},"thumbnailUrl":"http:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime.jpg","keywords":["Interview","Podcast","Tom Kaules","TomsTalkTime"],"articleSection":["Erfolgsimpulse","Erfolgsstorys","Lebensgl\u00fcck","Lebenslektionen","Motivation","Pers\u00f6nliche Erlebnisse","Spitzenleistung im Beruf","Spitzenleistung im Leben","Verbl\u00fcffendes &amp; Faszinierendes"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/","url":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/","name":"30-min\u00fctiges Podcast-Interview mit Steffen Kirchner","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/#primaryimage"},"image":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/#primaryimage"},"thumbnailUrl":"http:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime.jpg","datePublished":"2014-07-13T15:23:52+00:00","dateModified":"2018-09-17T13:55:07+00:00","description":"In diesem 30-min\u00fctigen Podcast-Interview spricht Steffen Kirchner \u00fcber seine gr\u00f6\u00dften Fehler, Erfolgsstrategien, Aha-Momente und Businesstipps. Viel Spa\u00df!","breadcrumb":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/#primaryimage","url":"http:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime.jpg","contentUrl":"http:\/\/www.steffenkirchner.de\/blog\/wp-content\/uploads\/2014\/07\/tomstalktime.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.steffenkirchner.de\/blog\/spezialausgabe-30-minuetiges-podcast-interview-mit-steffen-kirchner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.steffenkirchner.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Spezialausgabe: 30-min\u00fctiges Podcast-Interview mit Steffen Kirchner"}]},{"@type":"WebSite","@id":"https:\/\/www.steffenkirchner.de\/blog\/#website","url":"https:\/\/www.steffenkirchner.de\/blog\/","name":"Steffen Kirchner Blog","description":"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner","publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.steffenkirchner.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4","name":"Steffen Kirchner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","caption":"Steffen Kirchner"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.steffenkirchner.de","https:\/\/de-de.facebook.com\/steffenkirchner.de\/","https:\/\/www.instagram.com\/steffen.kirchner\/channel\/?hl=de","https:\/\/www.linkedin.com\/in\/steffen-kirchner\/?originalSubdomain=de","https:\/\/www.youtube.com\/channel\/UCZVCBY3k27CCmKxMNzLtedA"],"url":"https:\/\/www.steffenkirchner.de\/blog\/author\/admin\/"},false]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4QCGC-bL","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/comments?post=729"}],"version-history":[{"count":6,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/729\/revisions"}],"predecessor-version":[{"id":2053,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts\/729\/revisions\/2053"}],"wp:attachment":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/media?parent=729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/categories?post=729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/tags?post=729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}