{"id":63,"count":2,"description":"","link":"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/","name":"Aufschieberitis","slug":"aufschieberitis","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aufschieberitis - Blog von Motivationstrainer Steffen Kirchner<\/title>\n<meta name=\"description\" content=\"Lesen Sie hier alle Artikel mit dem Schlagwort Aufschieberitis aus dem Blog von Motivationstrainer Steffen Kirchner.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aufschieberitis - Blog von Motivationstrainer Steffen Kirchner\" \/>\n<meta property=\"og:description\" content=\"Lesen Sie hier alle Artikel mit dem Schlagwort Aufschieberitis aus dem Blog von Motivationstrainer Steffen Kirchner.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/\" \/>\n<meta property=\"og:site_name\" content=\"Steffen Kirchner Blog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/tag\\\/aufschieberitis\\\/\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/tag\\\/aufschieberitis\\\/\",\"name\":\"Aufschieberitis - Blog von Motivationstrainer Steffen Kirchner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\"},\"description\":\"Lesen Sie hier alle Artikel mit dem Schlagwort Aufschieberitis aus dem Blog von Motivationstrainer Steffen Kirchner.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/tag\\\/aufschieberitis\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/tag\\\/aufschieberitis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aufschieberitis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/\",\"name\":\"Steffen Kirchner Blog\",\"description\":\"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.steffenkirchner.de\\\/blog\\\/#\\\/schema\\\/person\\\/8f5fcb3bb099b1ac410606b0d07230d4\",\"name\":\"Steffen Kirchner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\",\"caption\":\"Steffen Kirchner\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.steffenkirchner.de\",\"https:\\\/\\\/de-de.facebook.com\\\/steffenkirchner.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/steffen.kirchner\\\/channel\\\/?hl=de\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/steffen-kirchner\\\/?originalSubdomain=de\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZVCBY3k27CCmKxMNzLtedA\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aufschieberitis - Blog von Motivationstrainer Steffen Kirchner","description":"Lesen Sie hier alle Artikel mit dem Schlagwort Aufschieberitis aus dem Blog von Motivationstrainer Steffen Kirchner.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/","og_locale":"de_DE","og_type":"article","og_title":"Aufschieberitis - Blog von Motivationstrainer Steffen Kirchner","og_description":"Lesen Sie hier alle Artikel mit dem Schlagwort Aufschieberitis aus dem Blog von Motivationstrainer Steffen Kirchner.","og_url":"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/","og_site_name":"Steffen Kirchner Blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/","url":"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/","name":"Aufschieberitis - Blog von Motivationstrainer Steffen Kirchner","isPartOf":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#website"},"description":"Lesen Sie hier alle Artikel mit dem Schlagwort Aufschieberitis aus dem Blog von Motivationstrainer Steffen Kirchner.","breadcrumb":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.steffenkirchner.de\/blog\/tag\/aufschieberitis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.steffenkirchner.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Aufschieberitis"}]},{"@type":"WebSite","@id":"https:\/\/www.steffenkirchner.de\/blog\/#website","url":"https:\/\/www.steffenkirchner.de\/blog\/","name":"Steffen Kirchner Blog","description":"Aktuelles von Speaker &amp; Motivationstrainer Steffen Kirchner","publisher":{"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.steffenkirchner.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.steffenkirchner.de\/blog\/#\/schema\/person\/8f5fcb3bb099b1ac410606b0d07230d4","name":"Steffen Kirchner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g","caption":"Steffen Kirchner"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/52970749e4a6e7afe182c48e32de72da8cfc31240b13252cbbe2925b7a4df8a0?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.steffenkirchner.de","https:\/\/de-de.facebook.com\/steffenkirchner.de\/","https:\/\/www.instagram.com\/steffen.kirchner\/channel\/?hl=de","https:\/\/www.linkedin.com\/in\/steffen-kirchner\/?originalSubdomain=de","https:\/\/www.youtube.com\/channel\/UCZVCBY3k27CCmKxMNzLtedA"]},false]}},"_links":{"self":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/tags\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.steffenkirchner.de\/blog\/wp-json\/wp\/v2\/posts?tags=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}